{"id":1859,"date":"2025-10-10T13:58:29","date_gmt":"2025-10-10T13:58:29","guid":{"rendered":"http:\/\/smartunit.be\/sites\/enghien-rue-ilya-prigogine-5-47-2\/"},"modified":"2025-12-11T10:32:20","modified_gmt":"2025-12-11T10:32:20","slug":"enghien-rue-ilya-prigogine-5-47-2","status":"publish","type":"sites","link":"https:\/\/smartunit.be\/fr\/sites\/enghien-rue-ilya-prigogine-5-47-2\/","title":{"rendered":"Enghien, Rue Ilya Prigogine 5-47"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","tags":[25,26],"class_list":["post-1859","sites","type-sites","status-publish","hentry","tag-a-lhonneur","tag-belgique"],"acf":[],"_links":{"self":[{"href":"https:\/\/smartunit.be\/fr\/wp-json\/wp\/v2\/sites\/1859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartunit.be\/fr\/wp-json\/wp\/v2\/sites"}],"about":[{"href":"https:\/\/smartunit.be\/fr\/wp-json\/wp\/v2\/types\/sites"}],"wp:attachment":[{"href":"https:\/\/smartunit.be\/fr\/wp-json\/wp\/v2\/media?parent=1859"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smartunit.be\/fr\/wp-json\/wp\/v2\/tags?post=1859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}